{"id":17380,"date":"2023-10-24T14:37:45","date_gmt":"2023-10-24T12:37:45","guid":{"rendered":"https:\/\/www.salviamolorso.it\/news\/"},"modified":"2024-06-10T12:21:30","modified_gmt":"2024-06-10T10:21:30","slug":"news","status":"publish","type":"page","link":"https:\/\/www.salviamolorso.it\/en\/news\/","title":{"rendered":"News"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0e2c49&#8243; min_height=&#8221;95px&#8221; height=&#8221;95px&#8221; max_height=&#8221;95px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;60px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;10px||0px||false|false&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#6a1815&#8243; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#6a1815&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#000000&#8243; header_3_font=&#8221;|700|||||||&#8221; header_3_text_color=&#8221;#262626&#8243; custom_margin=&#8221;||2px|||&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>NEWS &amp; PRESS RELEASES<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; border_color_bottom=&#8221;#6a1815&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blog fullwidth=&#8221;off&#8221; posts_number=&#8221;9&#8243; include_categories=&#8221;all&#8221; meta_date=&#8221;j F Y&#8221; excerpt_length=&#8221;300&#8243; show_author=&#8221;off&#8221; module_class=&#8221;dt-blog&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Alegreya Sans SC|700|||||||&#8221; header_font_size=&#8221;30px&#8221; body_text_align=&#8221;justify&#8221; meta_font=&#8221;Alegreya Sans SC||||||||&#8221; meta_text_color=&#8221;#6a1815&#8243; meta_font_size=&#8221;18px&#8221; read_more_font=&#8221;|600||on|||||&#8221; read_more_text_color=&#8221;#000000&#8243; read_more_font_size=&#8221;15px&#8221; pagination_font=&#8221;|600||on|||||&#8221; animation_style=&#8221;fade&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#494949&#8243; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#494949&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.salviamolorso.it\/wp-content\/uploads\/2023\/10\/short-SLO-white.png&#8221; title_text=&#8221;short-SLO-white&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; width=&#8221;40%&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;13px&#8221; text_line_height=&#8221;1.6em&#8221; custom_padding=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Save the Bear<\/strong><br \/>Association for the Conservation of the Marsican Brown Bear ONLUS<br \/>Olive Park Street, 11<br \/>65015 Montesilvano (PE)<br \/>Italy<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;13px&#8221; text_line_height=&#8221;1.6em&#8221; custom_padding=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>VAT NUMBER:<\/strong> 02189990688<br \/><strong>CF:<\/strong> 91117950682<br \/><strong>MAIL:<\/strong> info@salviamolorso.it<br \/><strong>PEC:<\/strong> ass.salviamolorso@pec.it<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;13px&#8221; text_line_height=&#8221;1.6em&#8221; custom_padding=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Donate now<br \/>Contact us<br \/>Privacy Policy<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;right&#8221; custom_padding=&#8221;||||false|false&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_enable_color=&#8221;on&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;twitter&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_enable_color=&#8221;on&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]X[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_enable_color=&#8221;on&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;linkedin&#8221; icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_enable_color=&#8221;on&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NEWS &amp; PRESS RELEASESSave the BearAssociation for the Conservation of the Marsican Brown Bear ONLUSOlive Park Street, 1165015 Montesilvano (PE)ItalyVAT NUMBER: 02189990688CF: 91117950682MAIL: info@salviamolorso.itPEC: ass.salviamolorso@pec.itDonate nowContact usPrivacy Policy<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17380","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News - Salviamo l&#039;Orso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salviamolorso.it\/news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News - Salviamo l&#039;Orso\" \/>\n<meta property=\"og:description\" content=\"NEWS &amp; PRESS RELEASESSave the BearAssociation for the Conservation of the Marsican Brown Bear ONLUSOlive Park Street, 1165015 Montesilvano (PE)ItalyVAT NUMBER: 02189990688CF: 91117950682MAIL: info@salviamolorso.itPEC: ass.salviamolorso@pec.itDonate nowContact usPrivacy Policy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salviamolorso.it\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Salviamo l&#039;Orso\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SalviamolOrso\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T10:21:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/news\\\/\",\"url\":\"https:\\\/\\\/www.salviamolorso.it\\\/news\\\/\",\"name\":\"News - Salviamo l&#039;Orso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/#website\"},\"datePublished\":\"2023-10-24T12:37:45+00:00\",\"dateModified\":\"2024-06-10T10:21:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salviamolorso.it\\\/news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salviamolorso.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/#website\",\"url\":\"https:\\\/\\\/www.salviamolorso.it\\\/\",\"name\":\"Salviamo l'Orso\",\"description\":\"Associazione per la Conservazione dell&#039;Orso Bruno Marsicano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salviamolorso.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/#organization\",\"name\":\"Salviamo l'Orso\",\"url\":\"https:\\\/\\\/www.salviamolorso.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salviamolorso.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo-SLO-black.png\",\"contentUrl\":\"https:\\\/\\\/www.salviamolorso.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/logo-SLO-black.png\",\"width\":899,\"height\":900,\"caption\":\"Salviamo l'Orso\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salviamolorso.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SalviamolOrso\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News - Salviamo l&#039;Orso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salviamolorso.it\/news\/","og_locale":"en_US","og_type":"article","og_title":"News - Salviamo l&#039;Orso","og_description":"NEWS &amp; PRESS RELEASESSave the BearAssociation for the Conservation of the Marsican Brown Bear ONLUSOlive Park Street, 1165015 Montesilvano (PE)ItalyVAT NUMBER: 02189990688CF: 91117950682MAIL: info@salviamolorso.itPEC: ass.salviamolorso@pec.itDonate nowContact usPrivacy Policy","og_url":"https:\/\/www.salviamolorso.it\/news\/","og_site_name":"Salviamo l&#039;Orso","article_publisher":"https:\/\/www.facebook.com\/SalviamolOrso","article_modified_time":"2024-06-10T10:21:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salviamolorso.it\/news\/","url":"https:\/\/www.salviamolorso.it\/news\/","name":"News - Salviamo l&#039;Orso","isPartOf":{"@id":"https:\/\/www.salviamolorso.it\/#website"},"datePublished":"2023-10-24T12:37:45+00:00","dateModified":"2024-06-10T10:21:30+00:00","breadcrumb":{"@id":"https:\/\/www.salviamolorso.it\/news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salviamolorso.it\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salviamolorso.it\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salviamolorso.it\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/www.salviamolorso.it\/#website","url":"https:\/\/www.salviamolorso.it\/","name":"Salviamo l'Orso","description":"Associazione per la Conservazione dell&#039;Orso Bruno Marsicano","publisher":{"@id":"https:\/\/www.salviamolorso.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salviamolorso.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.salviamolorso.it\/#organization","name":"Salviamo l'Orso","url":"https:\/\/www.salviamolorso.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.salviamolorso.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.salviamolorso.it\/wp-content\/uploads\/2023\/10\/logo-SLO-black.png","contentUrl":"https:\/\/www.salviamolorso.it\/wp-content\/uploads\/2023\/10\/logo-SLO-black.png","width":899,"height":900,"caption":"Salviamo l'Orso"},"image":{"@id":"https:\/\/www.salviamolorso.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SalviamolOrso"]}]}},"_links":{"self":[{"href":"https:\/\/www.salviamolorso.it\/en\/wp-json\/wp\/v2\/pages\/17380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salviamolorso.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.salviamolorso.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.salviamolorso.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salviamolorso.it\/en\/wp-json\/wp\/v2\/comments?post=17380"}],"version-history":[{"count":3,"href":"https:\/\/www.salviamolorso.it\/en\/wp-json\/wp\/v2\/pages\/17380\/revisions"}],"predecessor-version":[{"id":17941,"href":"https:\/\/www.salviamolorso.it\/en\/wp-json\/wp\/v2\/pages\/17380\/revisions\/17941"}],"wp:attachment":[{"href":"https:\/\/www.salviamolorso.it\/en\/wp-json\/wp\/v2\/media?parent=17380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}